{"id":9809,"date":"2024-09-26T13:07:48","date_gmt":"2024-09-26T11:07:48","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/"},"modified":"2024-09-26T13:07:48","modified_gmt":"2024-09-26T11:07:48","slug":"preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/","title":{"rendered":"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla"},"content":{"rendered":"<p>preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Roma Monte Mario preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vejano preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Anzio test visus videoterminalisti medico competente medicina del lavoro preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Guidonia Montecelio preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Genzano di Roma cartelle sanitarie preventivo dipendenti in azienda preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Roviano preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Cineto Romano preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Roma Sallustiano medicina del lavoro visite obbligatorie annuali<\/p>\n","protected":false},"excerpt":{"rendered":"<p>preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Roma Monte Mario preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vejano preventivo visite medico&hellip;&nbsp;<a href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-9809","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla -\" \/>\n<meta property=\"og:description\" content=\"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Roma Monte Mario preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vejano preventivo visite medico&hellip;&nbsp;Leggi tutto &raquo;preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T11:07:48+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/\",\"name\":\"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2024-09-26T11:07:48+00:00\",\"dateModified\":\"2024-09-26T11:07:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/","og_locale":"it_IT","og_type":"article","og_title":"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla -","og_description":"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Roma Monte Mario preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vejano preventivo visite medico&hellip;&nbsp;Leggi tutto &raquo;preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/","article_published_time":"2024-09-26T11:07:48+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/","name":"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2024-09-26T11:07:48+00:00","dateModified":"2024-09-26T11:07:48+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/preventivo-visite-medico-competente-medicina-del-lavoro-rilascio-idoneita-annuali-analisi-lavoratori-dipendenti-obbligatorie-cartella-sanitaria-visus-spirometria-audiometria-prelievo-sangue-a-dom-1427\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"preventivo visite medico competente medicina del lavoro rilascio idoneit\u00e0 annuali analisi lavoratori dipendenti obbligatorie cartella sanitaria visus spirometria audiometria prelievo sangue a domicilio a Vetralla"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/9809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=9809"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/9809\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=9809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=9809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=9809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}