{"id":8931,"date":"2024-09-26T12:17:56","date_gmt":"2024-09-26T10:17:56","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/"},"modified":"2024-09-26T12:17:56","modified_gmt":"2024-09-26T10:17:56","slug":"piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/","title":{"rendered":"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati"},"content":{"rendered":"<p>secondo le norme di buona tecnica contenute nell&#8217;allegato IX.  che tutti i propri dipendenti siano informati e Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Malattie Professionali pulizia, alla manutenzione, revisione e disinfezione  corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Piloti Di Navi Lavori In Mare In definitiva, dunque, il progettista, nell\u2019ambito della sua attivit\u00e0 professionale, \u00e8 tenuto all\u2019osservanza delle disposizioni legislative e regolamentari vigenti in materia di sicurezza e igiene dei luoghi di lavoro. corso sicurezza sul lavoro Rischio Specifico basso medio alto Malattie Professionali corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Macrosettore Trasporti Corso RLS: come garantire la salute e la sicurezza dei lavoratore corso sicurezza sul lavoro Rischio Specifico basso medio alto Polveri Sottili Aereodisperse Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Elettrico Cantieri corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Radiazioni Ottiche Artificiali Corso Sicurezza Sul Lavoro Addestramento Betomiera corso sicurezza sul lavoro Rischio Specifico basso medio alto Biologico della salute e sicurezza dei lavoratore.   Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Meccanico tutti gli aggiornamenti eventi fiere aggiornamento documento dvr sicurezza sul lavoro rinnovo verifica attestati di formazione commercialisti ingegneri architetti aziende grandi appalti pubblici e privati ditte appaltanti appaltatrici dipendenti dipendente lavoratore autonomo autonomi cooperative coop lavori stradali gestanti rischi specifici impiegato di ufficio barista cameriere autista studio studi notarili ingegneri architetti commercialisti convenzioni diventa partener franchising segretari<\/p>\n","protected":false},"excerpt":{"rendered":"<p>secondo le norme di buona tecnica contenute nell&#8217;allegato IX. che tutti i propri dipendenti siano informati e Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Malattie Professionali pulizia, alla manutenzione, revisione e disinfezione corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Piloti Di Navi&hellip;&nbsp;<a href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-8931","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati -\" \/>\n<meta property=\"og:description\" content=\"secondo le norme di buona tecnica contenute nell&#8217;allegato IX. che tutti i propri dipendenti siano informati e Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Malattie Professionali pulizia, alla manutenzione, revisione e disinfezione corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Piloti Di Navi&hellip;&nbsp;Leggi tutto &raquo;Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T10:17:56+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/\",\"name\":\"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2024-09-26T10:17:56+00:00\",\"dateModified\":\"2024-09-26T10:17:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/","og_locale":"it_IT","og_type":"article","og_title":"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati -","og_description":"secondo le norme di buona tecnica contenute nell&#8217;allegato IX. che tutti i propri dipendenti siano informati e Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Malattie Professionali pulizia, alla manutenzione, revisione e disinfezione corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Piloti Di Navi&hellip;&nbsp;Leggi tutto &raquo;Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/","article_published_time":"2024-09-26T10:17:56+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/","name":"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2024-09-26T10:17:56+00:00","dateModified":"2024-09-26T10:17:56+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-di-aggiornamento-coordinatore-sicurezza-fase-esecuzione-cse-online-accreditati-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"Piattaforma e-learning Corso di Aggiornamento Coordinatore Sicurezza fase Esecuzione (CSE) online accreditati"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/8931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=8931"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/8931\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=8931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=8931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=8931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}