{"id":598400,"date":"2026-05-13T19:23:57","date_gmt":"2026-05-13T17:23:57","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/"},"modified":"2026-05-13T19:23:57","modified_gmt":"2026-05-13T17:23:57","slug":"sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/","title":{"rendered":"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto"},"content":{"rendered":"<p>Piattaforma e-learning per la formazione professionale a Treviso Nuovo accordo stato regioni 2025 rspp esterno interno rls rlst preposto organismo paritetico associazione nazionale formatori Lavoratori a rischio Basso Medio Alto soggetto formatore italiani di aggiornamento obbligatorio corsi obbligatori rete preventivo aziende imprese edili edilizia agricole agricolatura tabella corsi tutti con nuovo Accordo 2025 formazione in salute e sicurezza rspp datore di lavoro Corsi per Gruista: Formazione Avanzata per la Sicurezza sul Lavoro Nuovo accordo stato regioni 2025 realt\u00e0 virtuale app formatori docenti rspp rls rlst preposto datore Evento formativo seminari gratuiti pi\u00f9 partecipati dai soggetti formatori italiani di aggiornamento obbligatorio ASPP\/RSPP (DL.81\/08, RSPP) e CSP\/CSE (DL.81\/08) Lezioni in aula realt\u00e0 virtuale Riconoscimento della formazione con nuovo Accordo 2025 corsi accreditati apri paprire  un centro di formazione ente scuola bilaterale associazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piattaforma e-learning per la formazione professionale a Treviso Nuovo accordo stato regioni 2025 rspp esterno interno rls rlst preposto organismo paritetico associazione nazionale formatori Lavoratori a rischio Basso Medio Alto soggetto formatore italiani di aggiornamento obbligatorio corsi obbligatori rete preventivo aziende imprese edili edilizia agricole agricolatura tabella corsi tutti con nuovo Accordo 2025 formazione in&hellip;&nbsp;<a href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-598400","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto -\" \/>\n<meta property=\"og:description\" content=\"Piattaforma e-learning per la formazione professionale a Treviso Nuovo accordo stato regioni 2025 rspp esterno interno rls rlst preposto organismo paritetico associazione nazionale formatori Lavoratori a rischio Basso Medio Alto soggetto formatore italiani di aggiornamento obbligatorio corsi obbligatori rete preventivo aziende imprese edili edilizia agricole agricolatura tabella corsi tutti con nuovo Accordo 2025 formazione in&hellip;&nbsp;Leggi tutto &raquo;Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T17:23:57+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/\",\"name\":\"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2026-05-13T17:23:57+00:00\",\"dateModified\":\"2026-05-13T17:23:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/","og_locale":"it_IT","og_type":"article","og_title":"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto -","og_description":"Piattaforma e-learning per la formazione professionale a Treviso Nuovo accordo stato regioni 2025 rspp esterno interno rls rlst preposto organismo paritetico associazione nazionale formatori Lavoratori a rischio Basso Medio Alto soggetto formatore italiani di aggiornamento obbligatorio corsi obbligatori rete preventivo aziende imprese edili edilizia agricole agricolatura tabella corsi tutti con nuovo Accordo 2025 formazione in&hellip;&nbsp;Leggi tutto &raquo;Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/","article_published_time":"2026-05-13T17:23:57+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/","name":"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2026-05-13T17:23:57+00:00","dateModified":"2026-05-13T17:23:57+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/sicurezza-e-prevenzione-incendi-per-la-gestione-di-feste-ed-eventi-in-un-bar-corso-formatore-rspp-datore-lavoratori-rischio-basso-medio-alto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"Sicurezza e prevenzione incendi per la gestione di feste ed eventi in un bar corso formatore rspp datore lavoratori rischio basso medio alto"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/598400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=598400"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/598400\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=598400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=598400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=598400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}