{"id":597980,"date":"2026-05-13T11:39:12","date_gmt":"2026-05-13T09:39:12","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/"},"modified":"2026-05-13T11:39:12","modified_gmt":"2026-05-13T09:39:12","slug":"corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/","title":{"rendered":"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso"},"content":{"rendered":"<p>Corsi di formazione in aula sulla sicurezza del lavoro del futuro: approfondisci e applica le innovazioni Nuovo accordo stato regioni 2025 corso formatori lavoratori datore parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) Corsi DLSPP fondi interprofessionali gratuiti gratis crediti formazione professionali cfp ecm fondi interprofessionali Formazione per il Personale Addetto alle Emergenze (PAE)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corsi di formazione in aula sulla sicurezza del lavoro del futuro: approfondisci e applica le innovazioni Nuovo accordo stato regioni 2025 corso formatori lavoratori datore parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) Corsi DLSPP fondi interprofessionali gratuiti gratis crediti formazione professionali cfp ecm fondi interprofessionali Formazione per il&hellip;&nbsp;<a href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-597980","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso -\" \/>\n<meta property=\"og:description\" content=\"Corsi di formazione in aula sulla sicurezza del lavoro del futuro: approfondisci e applica le innovazioni Nuovo accordo stato regioni 2025 corso formatori lavoratori datore parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) Corsi DLSPP fondi interprofessionali gratuiti gratis crediti formazione professionali cfp ecm fondi interprofessionali Formazione per il&hellip;&nbsp;Leggi tutto &raquo;Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T09:39:12+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/\",\"name\":\"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2026-05-13T09:39:12+00:00\",\"dateModified\":\"2026-05-13T09:39:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/","og_locale":"it_IT","og_type":"article","og_title":"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso -","og_description":"Corsi di formazione in aula sulla sicurezza del lavoro del futuro: approfondisci e applica le innovazioni Nuovo accordo stato regioni 2025 corso formatori lavoratori datore parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) Corsi DLSPP fondi interprofessionali gratuiti gratis crediti formazione professionali cfp ecm fondi interprofessionali Formazione per il&hellip;&nbsp;Leggi tutto &raquo;Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/","article_published_time":"2026-05-13T09:39:12+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/","name":"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2026-05-13T09:39:12+00:00","dateModified":"2026-05-13T09:39:12+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/13\/corso-datore-16-ore-corsi-di-formazione-online-e-nuovo-accordo-stato-regioni-2025-addetto-primo-soccorso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"Corso Datore 16 ore Corsi di Formazione Online e Nuovo Accordo Stato Regioni 2025: Addetto Primo Soccorso"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/597980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=597980"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/597980\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=597980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=597980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=597980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}