{"id":591265,"date":"2026-05-06T10:32:00","date_gmt":"2026-05-06T08:32:00","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/"},"modified":"2026-05-06T10:32:00","modified_gmt":"2026-05-06T08:32:00","slug":"quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/","title":{"rendered":"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato"},"content":{"rendered":"<p>Corso Datore di Lavoro Sicurezza sul Lavoro: Moduli Teorici sull&#8217;Utilizzo Sicuro delle PLE Corso intensivo sulla sicurezza sul lavoro: Formazione per Lavoratori Parte Generale e le normative del 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corso Datore di Lavoro Sicurezza sul Lavoro: Moduli Teorici sull&#8217;Utilizzo Sicuro delle PLE Corso intensivo sulla sicurezza sul lavoro: Formazione per Lavoratori Parte Generale e le normative del 2025<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-591265","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato -\" \/>\n<meta property=\"og:description\" content=\"Corso Datore di Lavoro Sicurezza sul Lavoro: Moduli Teorici sull&#8217;Utilizzo Sicuro delle PLE Corso intensivo sulla sicurezza sul lavoro: Formazione per Lavoratori Parte Generale e le normative del 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-06T08:32:00+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/\",\"name\":\"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2026-05-06T08:32:00+00:00\",\"dateModified\":\"2026-05-06T08:32:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/","og_locale":"it_IT","og_type":"article","og_title":"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato -","og_description":"Corso Datore di Lavoro Sicurezza sul Lavoro: Moduli Teorici sull&#8217;Utilizzo Sicuro delle PLE Corso intensivo sulla sicurezza sul lavoro: Formazione per Lavoratori Parte Generale e le normative del 2025","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/","article_published_time":"2026-05-06T08:32:00+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/","name":"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2026-05-06T08:32:00+00:00","dateModified":"2026-05-06T08:32:00+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2026\/05\/06\/quali-sono-gli-strumenti-di-autovalutazione-delle-competenze-acquisite-disponibili-per-i-partecipanti-ai-corsi-di-formazione-sulla-sicurezza-nuovo-accordo-stato-regioni-2025-corso-formatori-videoconf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"Quali sono gli strumenti di autovalutazione delle competenze acquisite disponibili per i partecipanti ai corsi di formazione sulla sicurezza? Nuovo accordo stato regioni 2025 corso formatori videoconferenza fad aula virtuale integrazione parte base generale Corsi per Datori di Lavoro con compiti di RSPP (DL SPP) rls rlst preposto datore lavoratori ddl dlspp rinnovo attestato"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/591265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=591265"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/591265\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=591265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=591265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=591265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}