{"id":22109,"date":"2024-09-27T06:21:44","date_gmt":"2024-09-27T04:21:44","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/"},"modified":"2024-09-27T06:21:44","modified_gmt":"2024-09-27T04:21:44","slug":"attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/","title":{"rendered":"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto)"},"content":{"rendered":"<p>Il presente decreto stabilisce l\u2019obbligo di uso.  &#8211; per i DPI contro gli shock elettrici Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Da Interferenze Duvri agricoltura azienda agricola come aprire cantiere edile temporaneo e mobile cantieri navali uffici ufficio srl spa preventivo preventivi haccp sicurezza sul lavoro  medicina del lavoro analsi acqua e legionella e alimenti batteriologica e chimica pozzi piscine condomini amministratori amministratore datore rspp di lavoro lavoratori lavoratore lavoratrice lavoratrici preposto preposti rls rlst pav pes pei coordinatore cps cse hse manager dirigente con delega di funzione stress lavoro correlato spazi confinanti dpi 1 2 3 prima seconda terza categoria lavori in alta quota patente patentino patentini gru ple trattore muletto mulettisti mulettista gruista con ruote trasporti su navi treni ple piattaforma elevabili movimentazione terra ruspa rischio chimico agenti fisico biologico movimentazione manuale carichi spazio confinato vibrazioni radiazioni solari ottiche polveri aereo disperse legionella macrosettore e codice ateco pesca estrazioni minerarie industria alimentare lavoro notturno duvri pos documento valutazione rischi manuale haccp standardizzato semplificato rinnovo rinnovare aggiornato aggiornamenti obbligatori obbligatorio obbligatoria documentazione valida validi per legge verificare scaduti scadenza durato corso quiz test finale domande e risposte. tutti gli aggiornamenti eventi fiere aggiornamento documento dvr sicurezza sul lavoro rinnovo verifica attestati di formazione commercialisti ingegneri architetti aziende grandi appalti pubblici e privati ditte appaltanti appaltatrici dipendenti dipendente lavoratore autonomo autonomi cooperative coop lavori stradali gestanti rischi specifici impiegato di ufficio barista cameriere autista studio studi notarili ingegneri architetti commercialisti convenzioni diventa partener franchising segretari<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presente decreto stabilisce l\u2019obbligo di uso. &#8211; per i DPI contro gli shock elettrici Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Da Interferenze Duvri agricoltura azienda agricola come aprire cantiere edile temporaneo e mobile cantieri navali uffici ufficio srl spa preventivo preventivi haccp sicurezza sul lavoro medicina del lavoro&hellip;&nbsp;<a href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto)<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-22109","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto) -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto) -\" \/>\n<meta property=\"og:description\" content=\"Il presente decreto stabilisce l\u2019obbligo di uso. &#8211; per i DPI contro gli shock elettrici Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Da Interferenze Duvri agricoltura azienda agricola come aprire cantiere edile temporaneo e mobile cantieri navali uffici ufficio srl spa preventivo preventivi haccp sicurezza sul lavoro medicina del lavoro&hellip;&nbsp;Leggi tutto &raquo;Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T04:21:44+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/\",\"name\":\"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto) -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2024-09-27T04:21:44+00:00\",\"dateModified\":\"2024-09-27T04:21:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto) -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/","og_locale":"it_IT","og_type":"article","og_title":"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto) -","og_description":"Il presente decreto stabilisce l\u2019obbligo di uso. &#8211; per i DPI contro gli shock elettrici Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Da Interferenze Duvri agricoltura azienda agricola come aprire cantiere edile temporaneo e mobile cantieri navali uffici ufficio srl spa preventivo preventivi haccp sicurezza sul lavoro medicina del lavoro&hellip;&nbsp;Leggi tutto &raquo;Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto)","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/","article_published_time":"2024-09-27T04:21:44+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/","name":"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto) -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2024-09-27T04:21:44+00:00","dateModified":"2024-09-27T04:21:44+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/27\/attestato-piattaforma-e-learning-corso-sicurezza-sul-lavoro-aggiornamento-patentino-carrello-elevatore-muletto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"Attestato Piattaforma e-learning Corso sicurezza sul lavoro aggiornamento patentino Carrello elevatore (Muletto)"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/22109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=22109"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/22109\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=22109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=22109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=22109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}