{"id":14614,"date":"2024-09-26T16:37:47","date_gmt":"2024-09-26T14:37:47","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/"},"modified":"2024-09-26T16:37:47","modified_gmt":"2024-09-26T14:37:47","slug":"attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/","title":{"rendered":"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1"},"content":{"rendered":"<p>Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Macrosettore Costruzioni Cantieri Edili Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Attrezzature Da Lavoro corso sicurezza sul lavoro Rischio Specifico basso medio alto Lavori In Strada Il DLgs 81\/08 ha abrogato il previgente D.P.R. n. 459\/96, che regolava la medesima materia e ha allineato la normativa in questione con quella del D.lgs. n.17\/2010, che ha recepito la cos\u00ec detta \u201cnuova direttiva macchine\u201d n.2006\/42\/CE contenente i requisiti di costruzione delle attrezzature di lavoro e dall\u2019altro. salute del lavoratore; 4. lavoratore anziani, corso sicurezza sul lavoro Rischio Specifico basso medio alto Amianto &#8212; il datore di lavoro delle imprese esecutrici I DPI devono essere impiegati corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Malattie Professionali Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Radiazioni Solari Outdoor Analisi dei rischi: corso sicurezza sul lavoro Rischio Specifico basso medio alto Biologico corso sicurezza sul lavoro Rischio Specifico basso medio alto Rischio Biologico &#8212; i costi per la sicurezza  Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Agricoltura Agricoltori corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Attrezzature Da Lavoro Regione Abruzzo Regione Basilicata Regione Calabria Regione Campania Regione Emilia-Romagna Regione Friuli Regione Venezia Regione Giulia Regione Lazio Regione Liguria Regione Lombardia Regione Marche Regione Molise Regione Piemonte Regione Puglia Regione Sardegna Regione Sicilia Regione Toscana Regione Trentino-Alto Regione Adige Regione Umbria Regione Valle Regione d&#8217;Aosta Regione Veneto Regione<br \/>\nL&#8217;Aquila Teramo Pescara Chieti Potenza Matera Catanzaro Cosenza Crotone Reggio Calabria Vibo Vale<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Macrosettore Costruzioni Cantieri Edili Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Attrezzature Da Lavoro corso sicurezza sul lavoro Rischio Specifico basso medio alto Lavori In Strada Il DLgs 81\/08 ha abrogato il previgente D.P.R. n. 459\/96, che regolava&hellip;&nbsp;<a href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-14614","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1 -\" \/>\n<meta property=\"og:description\" content=\"Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Macrosettore Costruzioni Cantieri Edili Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Attrezzature Da Lavoro corso sicurezza sul lavoro Rischio Specifico basso medio alto Lavori In Strada Il DLgs 81\/08 ha abrogato il previgente D.P.R. n. 459\/96, che regolava&hellip;&nbsp;Leggi tutto &raquo;Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T14:37:47+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/\",\"name\":\"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1 -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2024-09-26T14:37:47+00:00\",\"dateModified\":\"2024-09-26T14:37:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/","og_locale":"it_IT","og_type":"article","og_title":"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1 -","og_description":"Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Macrosettore Costruzioni Cantieri Edili Corso Sicurezza sul Lavoro datore di lavoro Rischio Specifico basso medio alto Attrezzature Da Lavoro corso sicurezza sul lavoro Rischio Specifico basso medio alto Lavori In Strada Il DLgs 81\/08 ha abrogato il previgente D.P.R. n. 459\/96, che regolava&hellip;&nbsp;Leggi tutto &raquo;Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/","article_published_time":"2024-09-26T14:37:47+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/","name":"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1 -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2024-09-26T14:37:47+00:00","dateModified":"2024-09-26T14:37:47+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/attestato-piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"Attestato Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 1"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/14614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=14614"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/14614\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=14614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=14614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=14614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}