{"id":14453,"date":"2024-09-26T16:31:41","date_gmt":"2024-09-26T14:31:41","guid":{"rendered":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/"},"modified":"2024-09-26T16:31:41","modified_gmt":"2024-09-26T14:31:41","slug":"piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati","status":"publish","type":"post","link":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/","title":{"rendered":"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati"},"content":{"rendered":"<p>corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Malattie Professionali Corso RSPP: la formazione per la sicurezza sul lavoro Si considerano costruiti a regola d&#8217;arte se sono realizzati  Le sessioni pratiche di addestramento vengono adattate in modo personalizzato, tenendo conto delle specifiche tipologie di lavori con funi. Ogni esercizio \u00e8 appositamente preparato e allestito per fornire una formazione completa ed efficace.   corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Amianto Il DPI \u00e8 certificato dalla dichiarazione di conformit\u00e0 Qualora non sia possibile evitare la movimentazione  Corso RLS in formato PDF agricoltura azienda agricola come aprire cantiere edile temporaneo e mobile cantieri navali uffici ufficio srl spa preventivo preventivi haccp sicurezza sul lavoro  medicina del lavoro analisi acqua e legionella e alimenti batteriologica e chimica pozzi piscine condomini amministratoti amministratore datore rspp di lavoro lavoratori lavoratore lavoratrice lavoratrici proposto preposti rls rlst pav pes pei coordinatore cps cse hse manager dirigente con delega di funzione stress lavoro correlato s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Malattie Professionali Corso RSPP: la formazione per la sicurezza sul lavoro Si considerano costruiti a regola d&#8217;arte se sono realizzati Le sessioni pratiche di addestramento vengono adattate in modo personalizzato, tenendo conto delle specifiche tipologie di lavori con funi. Ogni&hellip;&nbsp;<a href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-14453","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati -\" \/>\n<meta property=\"og:description\" content=\"corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Malattie Professionali Corso RSPP: la formazione per la sicurezza sul lavoro Si considerano costruiti a regola d&#8217;arte se sono realizzati Le sessioni pratiche di addestramento vengono adattate in modo personalizzato, tenendo conto delle specifiche tipologie di lavori con funi. Ogni&hellip;&nbsp;Leggi tutto &raquo;Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T14:31:41+00:00\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/\",\"name\":\"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati -\",\"isPartOf\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\"},\"datePublished\":\"2024-09-26T14:31:41+00:00\",\"dateModified\":\"2024-09-26T14:31:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#website\",\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/","og_locale":"it_IT","og_type":"article","og_title":"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati -","og_description":"corso sicurezza sul lavoro per datore di lavoro e lavoratore Rischio Specifico basso medio alto Malattie Professionali Corso RSPP: la formazione per la sicurezza sul lavoro Si considerano costruiti a regola d&#8217;arte se sono realizzati Le sessioni pratiche di addestramento vengono adattate in modo personalizzato, tenendo conto delle specifiche tipologie di lavori con funi. Ogni&hellip;&nbsp;Leggi tutto &raquo;Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati","og_url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/","article_published_time":"2024-09-26T14:31:41+00:00","author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/","url":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/","name":"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati -","isPartOf":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website"},"datePublished":"2024-09-26T14:31:41+00:00","dateModified":"2024-09-26T14:31:41+00:00","author":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc"},"breadcrumb":{"@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/2024\/09\/26\/piattaforma-e-learning-corso-aggiornamento-addetto-antincendio-livello-basso-medio-alto-2-online-accreditati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labservicesrl.it\/sicurezza\/"},{"@type":"ListItem","position":2,"name":"Piattaforma e-learning Corso aggiornamento addetto Antincendio livello basso medio alto 2 online accreditati"}]},{"@type":"WebSite","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#website","url":"https:\/\/www.labservicesrl.it\/sicurezza\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labservicesrl.it\/sicurezza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/89d515b5c433ea6277abe88575a4e3fc","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.labservicesrl.it\/sicurezza\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4d18f35a8712ba26d945306ab20748d9aff677d09772bdfdd2b8145f9097df?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.labservicesrl.it\/sicurezza\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/14453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/comments?post=14453"}],"version-history":[{"count":0,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/posts\/14453\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/media?parent=14453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/categories?post=14453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labservicesrl.it\/sicurezza\/wp-json\/wp\/v2\/tags?post=14453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}